{"id":4271,"date":"2016-06-14T15:16:51","date_gmt":"2016-06-14T15:16:51","guid":{"rendered":"https:\/\/new3.minisites.casadelmar.nl\/?p=4271"},"modified":"2023-05-02T11:50:18","modified_gmt":"2023-05-02T11:50:18","slug":"sendero-las-presas","status":"publish","type":"post","link":"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/","title":{"rendered":"Mijas Costa"},"content":{"rendered":"<p>Spiagge, relax, negozi e deliziose fritture di pesce: Mijas Costa \u00e8 il villaggio di pescatori ideale dove vivere una vacanza da sogno sulla costa. Mijas Costa ha oltre 11 chilometri di costa con spiagge incontaminate da non perdere assolutamente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Spiagge, relax, negozi e deliziose fritture di pesce: Mijas Costa \u00e8 il villaggio di pescatori ideale dove vivere una vacanza da sogno sulla costa. Mijas Costa ha oltre 11 chilometri di costa con spiagge incontaminate da non perdere... <a class=\"more-link\" href=\"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/\">Continua a leggere<\/a><\/p>","protected":false},"author":1,"featured_media":4351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mijas Costa - Marbella Bay Villa&#039;s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mijas Costa - Marbella Bay Villa&#039;s\" \/>\n<meta property=\"og:description\" content=\"Stranden, ontspanning, winkels en heerlijke gefrituurde vis: Mijas Costa is het ideale vissersdorp waar je kunt genieten van een droomvakantie aan de kust. Mijas Costa beschikt over ruim 11 kilometer aan kustlijn met ongerepte stranden die je zeker niet mag missen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/\" \/>\n<meta property=\"og:site_name\" content=\"Marbella Bay Villa&#039;s\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-14T15:16:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-02T11:50:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\"},\"headline\":\"Mijas Costa\",\"datePublished\":\"2016-06-14T15:16:51+00:00\",\"dateModified\":\"2023-05-02T11:50:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/\"},\"wordCount\":42,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marbellabay-villa.com\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2016\\\/06\\\/beach-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/\",\"url\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/\",\"name\":\"Mijas Costa - Marbella Bay Villa's\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marbellabay-villa.com\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2016\\\/06\\\/beach-1.jpg\",\"datePublished\":\"2016-06-14T15:16:51+00:00\",\"dateModified\":\"2023-05-02T11:50:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marbellabay-villa.com\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2016\\\/06\\\/beach-1.jpg\",\"contentUrl\":\"https:\\\/\\\/marbellabay-villa.com\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2016\\\/06\\\/beach-1.jpg\",\"width\":480,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/sendero-las-presas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marbellabay-villa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mijas Costa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/#website\",\"url\":\"https:\\\/\\\/marbellabay-villa.com\\\/\",\"name\":\"Marbella Bay Villa's\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marbellabay-villa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marbellabay-villa.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/minisites.casadelmar.nl\"],\"url\":\"https:\\\/\\\/marbellabay-villa.com\\\/it\\\/author\\\/admin_h89wrrhq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mijas Costa - Ville della Baia di Marbella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/","og_locale":"it_IT","og_type":"article","og_title":"Mijas Costa - Marbella Bay Villa's","og_description":"Stranden, ontspanning, winkels en heerlijke gefrituurde vis: Mijas Costa is het ideale vissersdorp waar je kunt genieten van een droomvakantie aan de kust. Mijas Costa beschikt over ruim 11 kilometer aan kustlijn met ongerepte stranden die je zeker niet mag missen.","og_url":"https:\/\/marbellabay-villa.com\/it\/sendero-las-presas\/","og_site_name":"Marbella Bay Villa's","article_published_time":"2016-06-14T15:16:51+00:00","article_modified_time":"2023-05-02T11:50:18+00:00","og_image":[{"width":480,"height":320,"url":"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#article","isPartOf":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/"},"author":{"name":"admin","@id":"https:\/\/marbellabay-villa.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed"},"headline":"Mijas Costa","datePublished":"2016-06-14T15:16:51+00:00","dateModified":"2023-05-02T11:50:18+00:00","mainEntityOfPage":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/"},"wordCount":42,"commentCount":0,"image":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#primaryimage"},"thumbnailUrl":"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg","articleSection":["Uncategorized"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marbellabay-villa.com\/sendero-las-presas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/","url":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/","name":"Mijas Costa - Ville della Baia di Marbella","isPartOf":{"@id":"https:\/\/marbellabay-villa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#primaryimage"},"image":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#primaryimage"},"thumbnailUrl":"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg","datePublished":"2016-06-14T15:16:51+00:00","dateModified":"2023-05-02T11:50:18+00:00","author":{"@id":"https:\/\/marbellabay-villa.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed"},"breadcrumb":{"@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marbellabay-villa.com\/sendero-las-presas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#primaryimage","url":"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg","contentUrl":"https:\/\/marbellabay-villa.com\/wp-content\/uploads\/sites\/24\/2016\/06\/beach-1.jpg","width":480,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/marbellabay-villa.com\/sendero-las-presas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marbellabay-villa.com\/"},{"@type":"ListItem","position":2,"name":"Mijas Costa"}]},{"@type":"WebSite","@id":"https:\/\/marbellabay-villa.com\/#website","url":"https:\/\/marbellabay-villa.com\/","name":"Ville della baia di Marbella","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marbellabay-villa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/marbellabay-villa.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed","name":"amministratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/minisites.casadelmar.nl"],"url":"https:\/\/marbellabay-villa.com\/it\/author\/admin_h89wrrhq\/"}]}},"_links":{"self":[{"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/posts\/4271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/comments?post=4271"}],"version-history":[{"count":5,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/posts\/4271\/revisions"}],"predecessor-version":[{"id":4352,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/posts\/4271\/revisions\/4352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/media\/4351"}],"wp:attachment":[{"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/media?parent=4271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/categories?post=4271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marbellabay-villa.com\/it\/wp-json\/wp\/v2\/tags?post=4271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}